{"id":42617,"date":"2019-12-02T13:27:18","date_gmt":"2019-12-02T04:27:18","guid":{"rendered":"https:\/\/www.temma.co.jp\/ozk014\/"},"modified":"2024-04-05T14:04:08","modified_gmt":"2024-04-05T05:04:08","slug":"ozk014","status":"publish","type":"post","link":"https:\/\/www.temma.co.jp\/ozk014\/","title":{"rendered":"OZK014Egg cup (L)"},"content":{"rendered":"<div class=\"loopimg\">\r\n\t<a href=\"https:\/\/www.temma.co.jp\/ozk014\/\"><img width=\"300\" height=\"300\" src=\"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014-300x300.png\" class=\"attachment-300x300 size-300x300\" alt=\"OZK014\" srcset=\"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014-300x300.png 300w, https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\r\n\t<\/div>\r\n\t<div class=\"loopexp\">\r\n\t\t<div class=\"field\"><\/div>\r\n\t<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"loopimg\">\r\n\t<a href=\"https:\/\/www.temma.co.jp\/ozk014\/\"><img width=\"300\" height=\"300\" src=\"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014-300x300.png\" class=\"attachment-300x300 size-300x300\" alt=\"OZK014\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014-300x300.png 300w, https:\/\/www.temma.co.jp\/wp-content\/uploads\/2019\/12\/ozk014.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\r\n\t<\/div>\r\n\t<div class=\"loopexp\">\r\n\t\t<div class=\"field\"><p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.temma.co.jp\/ozk014\/\">\u8a73\u3057\u304f\u306f\u30fb\u30fb\u30fb<\/a><\/p><\/div>\r\n\t<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_locale":"ja","_original_post":"42617","footnotes":""},"categories":[170,89,3],"tags":[],"class_list":["post-42617","post","type-post","status-publish","format-standard","hentry","category-fz05_ice_dessertware","category-item13_frozen","category-item","ja"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.temma.co.jp\/ozk014\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#article\",\"name\":\"OZK014Egg cup (L) | \\u5929\\u6e80\\u7d19\\u5668\",\"headline\":\"OZK014Egg cup (L)\",\"author\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/author\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/TEMMA_logo_s.png\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#articleImage\",\"width\":395,\"height\":60},\"datePublished\":\"2019-12-02T13:27:18+09:00\",\"dateModified\":\"2024-04-05T14:04:08+09:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#webpage\"},\"articleSection\":\"\\u30c7\\u30b6\\u30fc\\u30c8, \\u51b7\\u83d3\\u5bb9\\u5668, \\u5546\\u54c1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.temma.co.jp\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/#listItem\",\"name\":\"\\u5546\\u54c1\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/#listItem\",\"position\":2,\"name\":\"\\u5546\\u54c1\",\"item\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/#listItem\",\"name\":\"\\u5546\\u54c1\\u691c\\u7d22\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/#listItem\",\"position\":3,\"name\":\"\\u5546\\u54c1\\u691c\\u7d22\",\"item\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/#listItem\",\"name\":\"\\u51b7\\u83d3\\u5bb9\\u5668\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/#listItem\",\"name\":\"\\u5546\\u54c1\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/#listItem\",\"position\":4,\"name\":\"\\u51b7\\u83d3\\u5bb9\\u5668\",\"item\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/fz05_ice_dessertware\\\/#listItem\",\"name\":\"\\u30c7\\u30b6\\u30fc\\u30c8\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/#listItem\",\"name\":\"\\u5546\\u54c1\\u691c\\u7d22\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/fz05_ice_dessertware\\\/#listItem\",\"position\":5,\"name\":\"\\u30c7\\u30b6\\u30fc\\u30c8\",\"item\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/fz05_ice_dessertware\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#listItem\",\"name\":\"OZK014Egg cup (L)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/#listItem\",\"name\":\"\\u51b7\\u83d3\\u5bb9\\u5668\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#listItem\",\"position\":6,\"name\":\"OZK014Egg cup (L)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/en\\\/category\\\/item\\\/itemgenre\\\/item13_frozen\\\/fz05_ice_dessertware\\\/#listItem\",\"name\":\"\\u30c7\\u30b6\\u30fc\\u30c8\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#organization\",\"name\":\"\\u5929\\u6e80\\u7d19\\u5668\\u682a\\u5f0f\\u4f1a\\u793e\",\"description\":\"\\u304a\\u3044\\u3057\\u3044\\u98a8\\u666f\\u306e\\u306a\\u304b\\u306b\\u306fTEMMA\\u304c\\u3044\\u307e\\u3059\\u3002\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/TEMMA_logo_s.png\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#organizationLogo\",\"width\":395,\"height\":60},\"image\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/author\\\/#author\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/author\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#webpage\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/\",\"name\":\"OZK014Egg cup (L) | \\u5929\\u6e80\\u7d19\\u5668\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/ozk014\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/author\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/author\\\/#author\"},\"datePublished\":\"2019-12-02T13:27:18+09:00\",\"dateModified\":\"2024-04-05T14:04:08+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#website\",\"url\":\"https:\\\/\\\/www.temma.co.jp\\\/\",\"name\":\"\\u5929\\u6e80\\u7d19\\u5668\",\"description\":\"\\u304a\\u3044\\u3057\\u3044\\u98a8\\u666f\\u306e\\u306a\\u304b\\u306b\\u306fTEMMA\\u304c\\u3044\\u307e\\u3059\\u3002\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.temma.co.jp\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"OZK014Egg cup (L) | \u5929\u6e80\u7d19\u5668","description":"","canonical_url":"https:\/\/www.temma.co.jp\/ozk014\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.temma.co.jp\/ozk014\/#article","name":"OZK014Egg cup (L) | \u5929\u6e80\u7d19\u5668","headline":"OZK014Egg cup (L)","author":{"@id":"https:\/\/www.temma.co.jp\/author\/#author"},"publisher":{"@id":"https:\/\/www.temma.co.jp\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2022\/09\/TEMMA_logo_s.png","@id":"https:\/\/www.temma.co.jp\/#articleImage","width":395,"height":60},"datePublished":"2019-12-02T13:27:18+09:00","dateModified":"2024-04-05T14:04:08+09:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.temma.co.jp\/ozk014\/#webpage"},"isPartOf":{"@id":"https:\/\/www.temma.co.jp\/ozk014\/#webpage"},"articleSection":"\u30c7\u30b6\u30fc\u30c8, \u51b7\u83d3\u5bb9\u5668, \u5546\u54c1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.temma.co.jp\/ozk014\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp#listItem","position":1,"name":"Home","item":"https:\/\/www.temma.co.jp","nextItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/#listItem","name":"\u5546\u54c1"}},{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/#listItem","position":2,"name":"\u5546\u54c1","item":"https:\/\/www.temma.co.jp\/en\/category\/item\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/#listItem","name":"\u5546\u54c1\u691c\u7d22"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/#listItem","position":3,"name":"\u5546\u54c1\u691c\u7d22","item":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/#listItem","name":"\u51b7\u83d3\u5bb9\u5668"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/#listItem","name":"\u5546\u54c1"}},{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/#listItem","position":4,"name":"\u51b7\u83d3\u5bb9\u5668","item":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/#listItem","name":"\u30c7\u30b6\u30fc\u30c8"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/#listItem","name":"\u5546\u54c1\u691c\u7d22"}},{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/#listItem","position":5,"name":"\u30c7\u30b6\u30fc\u30c8","item":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/ozk014\/#listItem","name":"OZK014Egg cup (L)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/#listItem","name":"\u51b7\u83d3\u5bb9\u5668"}},{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/ozk014\/#listItem","position":6,"name":"OZK014Egg cup (L)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/#listItem","name":"\u30c7\u30b6\u30fc\u30c8"}}]},{"@type":"Organization","@id":"https:\/\/www.temma.co.jp\/#organization","name":"\u5929\u6e80\u7d19\u5668\u682a\u5f0f\u4f1a\u793e","description":"\u304a\u3044\u3057\u3044\u98a8\u666f\u306e\u306a\u304b\u306b\u306fTEMMA\u304c\u3044\u307e\u3059\u3002","url":"https:\/\/www.temma.co.jp\/","logo":{"@type":"ImageObject","url":"https:\/\/www.temma.co.jp\/wp-content\/uploads\/2022\/09\/TEMMA_logo_s.png","@id":"https:\/\/www.temma.co.jp\/ozk014\/#organizationLogo","width":395,"height":60},"image":{"@id":"https:\/\/www.temma.co.jp\/ozk014\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.temma.co.jp\/author\/#author","url":"https:\/\/www.temma.co.jp\/author\/"},{"@type":"WebPage","@id":"https:\/\/www.temma.co.jp\/ozk014\/#webpage","url":"https:\/\/www.temma.co.jp\/ozk014\/","name":"OZK014Egg cup (L) | \u5929\u6e80\u7d19\u5668","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.temma.co.jp\/#website"},"breadcrumb":{"@id":"https:\/\/www.temma.co.jp\/ozk014\/#breadcrumblist"},"author":{"@id":"https:\/\/www.temma.co.jp\/author\/#author"},"creator":{"@id":"https:\/\/www.temma.co.jp\/author\/#author"},"datePublished":"2019-12-02T13:27:18+09:00","dateModified":"2024-04-05T14:04:08+09:00"},{"@type":"WebSite","@id":"https:\/\/www.temma.co.jp\/#website","url":"https:\/\/www.temma.co.jp\/","name":"\u5929\u6e80\u7d19\u5668","description":"\u304a\u3044\u3057\u3044\u98a8\u666f\u306e\u306a\u304b\u306b\u306fTEMMA\u304c\u3044\u307e\u3059\u3002","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.temma.co.jp\/#organization"}}]}},"aioseo_meta_data":{"post_id":"42617","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 07:10:49","updated":"2022-09-22 00:55:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.temma.co.jp\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.temma.co.jp\/en\/category\/item\/\" title=\"\u5546\u54c1\">\u5546\u54c1<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/\" title=\"\u5546\u54c1\u691c\u7d22\">\u5546\u54c1\u691c\u7d22<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/\" title=\"\u51b7\u83d3\u5bb9\u5668\">\u51b7\u83d3\u5bb9\u5668<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/\" title=\"\u30c7\u30b6\u30fc\u30c8\">\u30c7\u30b6\u30fc\u30c8<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOZK014Egg cup (L)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.temma.co.jp"},{"label":"\u5546\u54c1","link":"https:\/\/www.temma.co.jp\/en\/category\/item\/"},{"label":"\u5546\u54c1\u691c\u7d22","link":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/"},{"label":"\u51b7\u83d3\u5bb9\u5668","link":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/"},{"label":"\u30c7\u30b6\u30fc\u30c8","link":"https:\/\/www.temma.co.jp\/en\/category\/item\/itemgenre\/item13_frozen\/fz05_ice_dessertware\/"},{"label":"OZK014Egg cup (L)","link":"https:\/\/www.temma.co.jp\/ozk014\/"}],"_links":{"self":[{"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/posts\/42617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/comments?post=42617"}],"version-history":[{"count":1,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/posts\/42617\/revisions"}],"predecessor-version":[{"id":42760,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/posts\/42617\/revisions\/42760"}],"wp:attachment":[{"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/media?parent=42617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/categories?post=42617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.temma.co.jp\/wp-json\/wp\/v2\/tags?post=42617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}